{"id":437,"date":"2020-07-06T18:43:39","date_gmt":"2020-07-06T18:43:39","guid":{"rendered":"https:\/\/parsons.edu\/integrated-design\/?p=437"},"modified":"2020-07-06T18:45:30","modified_gmt":"2020-07-06T18:45:30","slug":"the-space-between-exhibition-launch","status":"publish","type":"post","link":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/","title":{"rendered":"\u201cThe Space Between\u201c Exhibition Launch"},"content":{"rendered":"<p><iframe title=\"&quot;The Space Between&quot; IDp BFA Thesis Exhibition Launch\" src=\"https:\/\/player.vimeo.com\/video\/435772889?dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":40,"featured_media":441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[21],"tags":[],"class_list":["post-437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-remote-content"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Space Between Exhibition Launch<\/title>\n<meta name=\"description\" content=\"A celebration and discussion of the 2020 BFA IDp Thesis show with commentary by faculty and students.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Space Between Exhibition Launch\" \/>\n<meta property=\"og:description\" content=\"A celebration and discussion of the 2020 BFA IDp Thesis show with commentary by faculty and students.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/\" \/>\n<meta property=\"og:site_name\" content=\"Integrated Design\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-06T18:43:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-06T18:45:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/parsons.edu\/integrated-design\/wp-content\/uploads\/sites\/8\/2020\/07\/Screen-Shot-2020-07-06-at-2.34.20-PM.png\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"537\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"davym947\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"davym947\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/\"},\"author\":{\"name\":\"davym947\",\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/#\\\/schema\\\/person\\\/4a11f6699c2ddf592fc24c1516811122\"},\"headline\":\"\u201cThe Space Between\u201c Exhibition Launch\",\"datePublished\":\"2020-07-06T18:43:39+00:00\",\"dateModified\":\"2020-07-06T18:45:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/\"},\"wordCount\":10,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2020\\\/07\\\/Screen-Shot-2020-07-06-at-2.34.20-PM.png\",\"articleSection\":[\"Remote Content\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/\",\"url\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/\",\"name\":\"The Space Between Exhibition Launch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2020\\\/07\\\/Screen-Shot-2020-07-06-at-2.34.20-PM.png\",\"datePublished\":\"2020-07-06T18:43:39+00:00\",\"dateModified\":\"2020-07-06T18:45:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/#\\\/schema\\\/person\\\/4a11f6699c2ddf592fc24c1516811122\"},\"description\":\"A celebration and discussion of the 2020 BFA IDp Thesis show with commentary by faculty and students.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2020\\\/07\\\/Screen-Shot-2020-07-06-at-2.34.20-PM.png\",\"contentUrl\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2020\\\/07\\\/Screen-Shot-2020-07-06-at-2.34.20-PM.png\",\"width\":948,\"height\":537},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/the-space-between-exhibition-launch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cThe Space Between\u201c Exhibition Launch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/#website\",\"url\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/\",\"name\":\"Integrated Design\",\"description\":\"BFA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/#\\\/schema\\\/person\\\/4a11f6699c2ddf592fc24c1516811122\",\"name\":\"davym947\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f4f9ecd6c5ca8eee33b5f60da6ada260ca28c95ebc079a7ccb32d08f478be6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f4f9ecd6c5ca8eee33b5f60da6ada260ca28c95ebc079a7ccb32d08f478be6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f4f9ecd6c5ca8eee33b5f60da6ada260ca28c95ebc079a7ccb32d08f478be6b?s=96&d=mm&r=g\",\"caption\":\"davym947\"},\"url\":\"https:\\\/\\\/parsons.edu\\\/integrated-design\\\/author\\\/davym947\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Space Between Exhibition Launch","description":"A celebration and discussion of the 2020 BFA IDp Thesis show with commentary by faculty and students.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/","og_locale":"en_US","og_type":"article","og_title":"The Space Between Exhibition Launch","og_description":"A celebration and discussion of the 2020 BFA IDp Thesis show with commentary by faculty and students.","og_url":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/","og_site_name":"Integrated Design","article_published_time":"2020-07-06T18:43:39+00:00","article_modified_time":"2020-07-06T18:45:30+00:00","og_image":[{"width":948,"height":537,"url":"https:\/\/parsons.edu\/integrated-design\/wp-content\/uploads\/sites\/8\/2020\/07\/Screen-Shot-2020-07-06-at-2.34.20-PM.png","type":"image\/png"}],"author":"davym947","twitter_card":"summary_large_image","twitter_misc":{"Written by":"davym947"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/#article","isPartOf":{"@id":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/"},"author":{"name":"davym947","@id":"https:\/\/parsons.edu\/integrated-design\/#\/schema\/person\/4a11f6699c2ddf592fc24c1516811122"},"headline":"\u201cThe Space Between\u201c Exhibition Launch","datePublished":"2020-07-06T18:43:39+00:00","dateModified":"2020-07-06T18:45:30+00:00","mainEntityOfPage":{"@id":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/"},"wordCount":10,"commentCount":0,"image":{"@id":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/#primaryimage"},"thumbnailUrl":"https:\/\/parsons.edu\/integrated-design\/wp-content\/uploads\/sites\/8\/2020\/07\/Screen-Shot-2020-07-06-at-2.34.20-PM.png","articleSection":["Remote Content"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/","url":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/","name":"The Space Between Exhibition Launch","isPartOf":{"@id":"https:\/\/parsons.edu\/integrated-design\/#website"},"primaryImageOfPage":{"@id":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/#primaryimage"},"image":{"@id":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/#primaryimage"},"thumbnailUrl":"https:\/\/parsons.edu\/integrated-design\/wp-content\/uploads\/sites\/8\/2020\/07\/Screen-Shot-2020-07-06-at-2.34.20-PM.png","datePublished":"2020-07-06T18:43:39+00:00","dateModified":"2020-07-06T18:45:30+00:00","author":{"@id":"https:\/\/parsons.edu\/integrated-design\/#\/schema\/person\/4a11f6699c2ddf592fc24c1516811122"},"description":"A celebration and discussion of the 2020 BFA IDp Thesis show with commentary by faculty and students.","breadcrumb":{"@id":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/#primaryimage","url":"https:\/\/parsons.edu\/integrated-design\/wp-content\/uploads\/sites\/8\/2020\/07\/Screen-Shot-2020-07-06-at-2.34.20-PM.png","contentUrl":"https:\/\/parsons.edu\/integrated-design\/wp-content\/uploads\/sites\/8\/2020\/07\/Screen-Shot-2020-07-06-at-2.34.20-PM.png","width":948,"height":537},{"@type":"BreadcrumbList","@id":"https:\/\/parsons.edu\/integrated-design\/the-space-between-exhibition-launch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/parsons.edu\/integrated-design\/"},{"@type":"ListItem","position":2,"name":"\u201cThe Space Between\u201c Exhibition Launch"}]},{"@type":"WebSite","@id":"https:\/\/parsons.edu\/integrated-design\/#website","url":"https:\/\/parsons.edu\/integrated-design\/","name":"Integrated Design","description":"BFA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/parsons.edu\/integrated-design\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/parsons.edu\/integrated-design\/#\/schema\/person\/4a11f6699c2ddf592fc24c1516811122","name":"davym947","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6f4f9ecd6c5ca8eee33b5f60da6ada260ca28c95ebc079a7ccb32d08f478be6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6f4f9ecd6c5ca8eee33b5f60da6ada260ca28c95ebc079a7ccb32d08f478be6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f4f9ecd6c5ca8eee33b5f60da6ada260ca28c95ebc079a7ccb32d08f478be6b?s=96&d=mm&r=g","caption":"davym947"},"url":"https:\/\/parsons.edu\/integrated-design\/author\/davym947\/"}]}},"_links":{"self":[{"href":"https:\/\/parsons.edu\/integrated-design\/wp-json\/wp\/v2\/posts\/437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parsons.edu\/integrated-design\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/parsons.edu\/integrated-design\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/parsons.edu\/integrated-design\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/parsons.edu\/integrated-design\/wp-json\/wp\/v2\/comments?post=437"}],"version-history":[{"count":1,"href":"https:\/\/parsons.edu\/integrated-design\/wp-json\/wp\/v2\/posts\/437\/revisions"}],"predecessor-version":[{"id":440,"href":"https:\/\/parsons.edu\/integrated-design\/wp-json\/wp\/v2\/posts\/437\/revisions\/440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/parsons.edu\/integrated-design\/wp-json\/wp\/v2\/media\/441"}],"wp:attachment":[{"href":"https:\/\/parsons.edu\/integrated-design\/wp-json\/wp\/v2\/media?parent=437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/parsons.edu\/integrated-design\/wp-json\/wp\/v2\/categories?post=437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/parsons.edu\/integrated-design\/wp-json\/wp\/v2\/tags?post=437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}